{"id":578,"date":"2022-09-11T11:41:02","date_gmt":"2022-09-11T11:41:02","guid":{"rendered":"https:\/\/praxisreview.de\/?page_id=578"},"modified":"2022-09-11T12:00:01","modified_gmt":"2022-09-11T12:00:01","slug":"impressum","status":"publish","type":"page","link":"https:\/\/praxisreview.de\/index.php\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"578\" class=\"elementor elementor-578\">\n\t\t\t\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-90354a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90354a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-254f373\" data-id=\"254f373\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e4be42 elementor-widget elementor-widget-text-editor\" data-id=\"9e4be42\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.1 - 14-08-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h1>Impressum<\/h1><h2>Angaben gem\u00e4\u00df \u00a7 5 TMG<\/h2><p>Rankingdocs GmbH<br \/>Ifflandstra\u00dfe 4<br \/>22087 Hamburg<\/p><p>Handelsregister: HRB 165054<br \/>Registergericht: Amtsgericht Hamburg<\/p><p><strong>Vertreten durch:<\/strong><br \/>Ren\u00e9 Ramcke<br \/>Sebastian Weidner<\/p><h2>Kontakt<\/h2><p>Telefon: 040 \/ 33468210<br \/>E-Mail: info (at) praxisreview.de<\/p><h2>Umsatzsteuer-ID<\/h2><p>Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz:<br \/>DE335133396<\/p><h2>Redaktionell Verantwortlicher<\/h2><p>Ren\u00e9 Ramcke<br \/>Ifflandstra\u00dfe 4<br \/>22087 Hamburg<\/p><h2>Verbraucher\u00adstreit\u00adbeilegung\/Universal\u00adschlichtungs\u00adstelle<\/h2><p>Wir sind nicht bereit oder verpflichtet, an Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teilzunehmen.<\/p><h3>Haftung f\u00fcr Inhalte<\/h3><p>Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte fremde Informationen zu \u00fcberwachen oder nach Umst\u00e4nden zu forschen, die auf eine rechtswidrige T\u00e4tigkeit hinweisen.<\/p><p>Verpflichtungen zur Entfernung oder Sperrung der Nutzung von Informationen nach den allgemeinen Gesetzen bleiben hiervon unber\u00fchrt. Eine diesbez\u00fcgliche Haftung ist jedoch erst ab dem Zeitpunkt der Kenntnis einer konkreten Rechtsverletzung m\u00f6glich. Bei Bekanntwerden von entsprechenden Rechtsverletzungen werden wir diese Inhalte umgehend entfernen.<\/p><h3>Haftung f\u00fcr Links<\/h3><p>Unser Angebot enth\u00e4lt Links zu externen Websites Dritter, auf deren Inhalte wir keinen Einfluss haben. Deshalb k\u00f6nnen wir f\u00fcr diese fremden Inhalte auch keine Gew\u00e4hr \u00fcbernehmen. F\u00fcr die Inhalte der verlinkten Seiten ist stets der jeweilige Anbieter oder Betreiber der Seiten verantwortlich. Die verlinkten Seiten wurden zum Zeitpunkt der Verlinkung auf m\u00f6gliche Rechtsverst\u00f6\u00dfe \u00fcberpr\u00fcft. Rechtswidrige Inhalte waren zum Zeitpunkt der Verlinkung nicht erkennbar.<\/p><p>Eine permanente inhaltliche Kontrolle der verlinkten Seiten ist jedoch ohne konkrete Anhaltspunkte einer Rechtsverletzung nicht zumutbar. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Links umgehend entfernen.<\/p><h3>Urheberrecht<\/h3><p>Die durch die Seitenbetreiber erstellten Inhalte und Werke auf diesen Seiten unterliegen dem deutschen Urheberrecht. Die Vervielf\u00e4ltigung, Bearbeitung, Verbreitung und jede Art der Verwertung au\u00dferhalb der Grenzen des Urheberrechtes bed\u00fcrfen der schriftlichen Zustimmung des jeweiligen Autors bzw. Erstellers. Downloads und Kopien dieser Seite sind nur f\u00fcr den privaten, nicht kommerziellen Gebrauch gestattet.<\/p><p>Soweit die Inhalte auf dieser Seite nicht vom Betreiber erstellt wurden, werden die Urheberrechte Dritter beachtet. Insbesondere werden Inhalte Dritter als solche gekennzeichnet. Sollten Sie trotzdem auf eine Urheberrechtsverletzung aufmerksam werden, bitten wir um einen entsprechenden Hinweis. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Inhalte umgehend entfernen.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Impressum Angaben gem\u00e4\u00df \u00a7 5 TMG Rankingdocs GmbHIfflandstra\u00dfe 422087 Hamburg Handelsregister: HRB 165054Registergericht: Amtsgericht Hamburg Vertreten durch:Ren\u00e9 RamckeSebastian Weidner Kontakt Telefon: 040 \/ 33468210E-Mail: info (at) praxisreview.de Umsatzsteuer-ID Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz:DE335133396 Redaktionell Verantwortlicher Ren\u00e9 RamckeIfflandstra\u00dfe 422087 Hamburg Verbraucher\u00adstreit\u00adbeilegung\/Universal\u00adschlichtungs\u00adstelle Wir sind nicht bereit oder verpflichtet, an Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teilzunehmen. Haftung f\u00fcr &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/praxisreview.de\/index.php\/impressum\/\"> <span class=\"screen-reader-text\">Impressum<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-578","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Impressum - Praxisreview<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impressum - Praxisreview\" \/>\n<meta property=\"og:description\" content=\"Impressum Angaben gem\u00e4\u00df \u00a7 5 TMG Rankingdocs GmbHIfflandstra\u00dfe 422087 Hamburg Handelsregister: HRB 165054Registergericht: Amtsgericht Hamburg Vertreten durch:Ren\u00e9 RamckeSebastian Weidner Kontakt Telefon: 040 \/ 33468210E-Mail: info (at) praxisreview.de Umsatzsteuer-ID Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz:DE335133396 Redaktionell Verantwortlicher Ren\u00e9 RamckeIfflandstra\u00dfe 422087 Hamburg Verbraucher\u00adstreit\u00adbeilegung\/Universal\u00adschlichtungs\u00adstelle Wir sind nicht bereit oder verpflichtet, an Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teilzunehmen. Haftung f\u00fcr &hellip; Impressum Weiterlesen &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/praxisreview.de\/index.php\/impressum\/\" \/>\n<meta property=\"og:site_name\" content=\"Praxisreview\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-11T12:00:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/praxisreview.de\/index.php\/impressum\/\",\"url\":\"https:\/\/praxisreview.de\/index.php\/impressum\/\",\"name\":\"Impressum - Praxisreview\",\"isPartOf\":{\"@id\":\"https:\/\/praxisreview.de\/#website\"},\"datePublished\":\"2022-09-11T11:41:02+00:00\",\"dateModified\":\"2022-09-11T12:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/praxisreview.de\/index.php\/impressum\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/praxisreview.de\/index.php\/impressum\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/praxisreview.de\/index.php\/impressum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/praxisreview.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impressum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/praxisreview.de\/#website\",\"url\":\"https:\/\/praxisreview.de\/\",\"name\":\"Praxisreview\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/praxisreview.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/praxisreview.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/praxisreview.de\/#organization\",\"name\":\"Praxisreview\",\"url\":\"https:\/\/praxisreview.de\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/praxisreview.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/praxisreview.de\/wp-content\/uploads\/2022\/08\/logo-praxisreview-vorlaeufig.png\",\"contentUrl\":\"https:\/\/praxisreview.de\/wp-content\/uploads\/2022\/08\/logo-praxisreview-vorlaeufig.png\",\"width\":1569,\"height\":343,\"caption\":\"Praxisreview\"},\"image\":{\"@id\":\"https:\/\/praxisreview.de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impressum - Praxisreview","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Impressum - Praxisreview","og_description":"Impressum Angaben gem\u00e4\u00df \u00a7 5 TMG Rankingdocs GmbHIfflandstra\u00dfe 422087 Hamburg Handelsregister: HRB 165054Registergericht: Amtsgericht Hamburg Vertreten durch:Ren\u00e9 RamckeSebastian Weidner Kontakt Telefon: 040 \/ 33468210E-Mail: info (at) praxisreview.de Umsatzsteuer-ID Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz:DE335133396 Redaktionell Verantwortlicher Ren\u00e9 RamckeIfflandstra\u00dfe 422087 Hamburg Verbraucher\u00adstreit\u00adbeilegung\/Universal\u00adschlichtungs\u00adstelle Wir sind nicht bereit oder verpflichtet, an Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teilzunehmen. Haftung f\u00fcr &hellip; Impressum Weiterlesen &raquo;","og_url":"https:\/\/praxisreview.de\/index.php\/impressum\/","og_site_name":"Praxisreview","article_modified_time":"2022-09-11T12:00:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/praxisreview.de\/index.php\/impressum\/","url":"https:\/\/praxisreview.de\/index.php\/impressum\/","name":"Impressum - Praxisreview","isPartOf":{"@id":"https:\/\/praxisreview.de\/#website"},"datePublished":"2022-09-11T11:41:02+00:00","dateModified":"2022-09-11T12:00:01+00:00","breadcrumb":{"@id":"https:\/\/praxisreview.de\/index.php\/impressum\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/praxisreview.de\/index.php\/impressum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/praxisreview.de\/index.php\/impressum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/praxisreview.de\/"},{"@type":"ListItem","position":2,"name":"Impressum"}]},{"@type":"WebSite","@id":"https:\/\/praxisreview.de\/#website","url":"https:\/\/praxisreview.de\/","name":"Praxisreview","description":"Just another WordPress site","publisher":{"@id":"https:\/\/praxisreview.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/praxisreview.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/praxisreview.de\/#organization","name":"Praxisreview","url":"https:\/\/praxisreview.de\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/praxisreview.de\/#\/schema\/logo\/image\/","url":"https:\/\/praxisreview.de\/wp-content\/uploads\/2022\/08\/logo-praxisreview-vorlaeufig.png","contentUrl":"https:\/\/praxisreview.de\/wp-content\/uploads\/2022\/08\/logo-praxisreview-vorlaeufig.png","width":1569,"height":343,"caption":"Praxisreview"},"image":{"@id":"https:\/\/praxisreview.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/praxisreview.de\/index.php\/wp-json\/wp\/v2\/pages\/578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/praxisreview.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/praxisreview.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/praxisreview.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/praxisreview.de\/index.php\/wp-json\/wp\/v2\/comments?post=578"}],"version-history":[{"count":14,"href":"https:\/\/praxisreview.de\/index.php\/wp-json\/wp\/v2\/pages\/578\/revisions"}],"predecessor-version":[{"id":606,"href":"https:\/\/praxisreview.de\/index.php\/wp-json\/wp\/v2\/pages\/578\/revisions\/606"}],"wp:attachment":[{"href":"https:\/\/praxisreview.de\/index.php\/wp-json\/wp\/v2\/media?parent=578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}